{"id":26,"count":5,"description":"","link":"https:\/\/severnwishes.co.uk\/wordpress\/category\/perfume\/","name":"Perfume","slug":"perfume","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/severnwishes.co.uk\/wordpress\/wp-json\/wp\/v2\/categories\/26"}],"collection":[{"href":"https:\/\/severnwishes.co.uk\/wordpress\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/severnwishes.co.uk\/wordpress\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/severnwishes.co.uk\/wordpress\/wp-json\/wp\/v2\/posts?categories=26"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}